{"id":5198,"date":"2023-01-30T13:09:54","date_gmt":"2023-01-30T12:09:54","guid":{"rendered":"https:\/\/airport-clinic.de\/?p=5198"},"modified":"2023-01-30T13:11:33","modified_gmt":"2023-01-30T12:11:33","slug":"schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch","status":"publish","type":"post","link":"https:\/\/airport-clinic.de\/en\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/","title":{"rendered":"Schmerzfreie Zahnbehandlung bei Angstpatienten: Dr. Andreas Jauch"},"content":{"rendered":"<style type=\"text\/css\"><\/style>\n<p>Jeder sechste Mensch hat Angst vor dem Zahnarztbesuch und verzichtet darauf, obwohl gepflegte Z\u00e4hne die Lebensqualit\u00e4t verbessern. Dr. med. Andreas Jauch, Leiter der AirportClinic Freising bei M\u00fcnchen, ist ein Experte f\u00fcr Angstpatienten und sorgt daf\u00fcr, dass diese entspannt und schmerzfrei behandelt werden. Durch Vorabgespr\u00e4che gewinnt er das Vertrauen seiner Patienten.<\/p>\n\n\n\n<p>Was ist die Ursache f\u00fcr die Angst vor dem Zahnarztbesuch? Wie kann der erste Praxisbesuch erleichtert werden? Alternativen zu Spritzen f\u00fcr Schmerzfreiheit? Wie aufwendig ist das Planungskonzept f\u00fcr Angstpatienten? Kann man seine Angst verlieren? Was ist eine Desensibilisierung? Doktor Jauch gibt Rat.<\/p>\n\n\n<p><script class=\"podigee-podcast-player\" src=\"https:\/\/player.podigee-cdn.net\/podcast-player\/javascripts\/podigee-podcast-player.js\" data-configuration=\"https:\/\/primomedico-fachaerzte-talk.podigee.io\/86-zahnarzt-dr-andreas-jauch\/embed?context=external\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeder sechste Mensch hat Angst vor dem Zahnarztbesuch und verzichtet darauf, obwohl gepflegte Z\u00e4hne die Lebensqualit\u00e4t verbessern. Dr. med. Andreas Jauch, Leiter der AirportClinic Freising bei M\u00fcnchen, ist ein Experte f\u00fcr Angstpatienten und sorgt daf\u00fcr, dass diese entspannt und schmerzfrei behandelt werden. Durch Vorabgespr\u00e4che gewinnt er das Vertrauen seiner Patienten. Was ist die Ursache f\u00fcr&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Schmerzfreie Zahnbehandlung bei Angstpatienten: Dr. Andreas Jauch - AirportClinic Freising<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schmerzfreie Zahnbehandlung bei Angstpatienten: Dr. Andreas Jauch - AirportClinic Freising\" \/>\n<meta property=\"og:description\" content=\"Jeder sechste Mensch hat Angst vor dem Zahnarztbesuch und verzichtet darauf, obwohl gepflegte Z\u00e4hne die Lebensqualit\u00e4t verbessern. Dr. med. Andreas Jauch, Leiter der AirportClinic Freising bei M\u00fcnchen, ist ein Experte f\u00fcr Angstpatienten und sorgt daf\u00fcr, dass diese entspannt und schmerzfrei behandelt werden. Durch Vorabgespr\u00e4che gewinnt er das Vertrauen seiner Patienten. Was ist die Ursache f\u00fcr...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/\" \/>\n<meta property=\"og:site_name\" content=\"AirportClinic Freising\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-30T12:09:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-30T12:11:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/airport-clinic.de\/wp-content\/uploads\/2022\/06\/6baa14f7-b0c1-44f0-98e4-437a957f3b8e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. med. Andreas Jauch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. med. Andreas Jauch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/\",\"url\":\"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/\",\"name\":\"Schmerzfreie Zahnbehandlung bei Angstpatienten: Dr. Andreas Jauch - AirportClinic Freising\",\"isPartOf\":{\"@id\":\"https:\/\/airport-clinic.de\/en\/#website\"},\"datePublished\":\"2023-01-30T12:09:54+00:00\",\"dateModified\":\"2023-01-30T12:11:33+00:00\",\"author\":{\"@id\":\"https:\/\/airport-clinic.de\/en\/#\/schema\/person\/43538e821127f36ed10b3d5e3709b3e3\"},\"breadcrumb\":{\"@id\":\"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/airport-clinic.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schmerzfreie Zahnbehandlung bei Angstpatienten: Dr. Andreas Jauch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/airport-clinic.de\/en\/#website\",\"url\":\"https:\/\/airport-clinic.de\/en\/\",\"name\":\"AirportClinic Freising\",\"description\":\"Zentrum f\u00fcr Zahn-, Mund-, Kieferheilkunde und \u00e4sthetische Chirurgie MVZ GmbH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/airport-clinic.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/airport-clinic.de\/en\/#\/schema\/person\/43538e821127f36ed10b3d5e3709b3e3\",\"name\":\"Dr. med. Andreas Jauch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/airport-clinic.de\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4c61a56fd3071af7ddad2b2f0dd7ba04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4c61a56fd3071af7ddad2b2f0dd7ba04?s=96&d=mm&r=g\",\"caption\":\"Dr. med. Andreas Jauch\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schmerzfreie Zahnbehandlung bei Angstpatienten: Dr. Andreas Jauch - AirportClinic Freising","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/","og_locale":"en_US","og_type":"article","og_title":"Schmerzfreie Zahnbehandlung bei Angstpatienten: Dr. Andreas Jauch - AirportClinic Freising","og_description":"Jeder sechste Mensch hat Angst vor dem Zahnarztbesuch und verzichtet darauf, obwohl gepflegte Z\u00e4hne die Lebensqualit\u00e4t verbessern. Dr. med. Andreas Jauch, Leiter der AirportClinic Freising bei M\u00fcnchen, ist ein Experte f\u00fcr Angstpatienten und sorgt daf\u00fcr, dass diese entspannt und schmerzfrei behandelt werden. Durch Vorabgespr\u00e4che gewinnt er das Vertrauen seiner Patienten. Was ist die Ursache f\u00fcr...","og_url":"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/","og_site_name":"AirportClinic Freising","article_published_time":"2023-01-30T12:09:54+00:00","article_modified_time":"2023-01-30T12:11:33+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/airport-clinic.de\/wp-content\/uploads\/2022\/06\/6baa14f7-b0c1-44f0-98e4-437a957f3b8e.jpg","type":"image\/jpeg"}],"author":"Dr. med. Andreas Jauch","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dr. med. Andreas Jauch","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/","url":"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/","name":"Schmerzfreie Zahnbehandlung bei Angstpatienten: Dr. Andreas Jauch - AirportClinic Freising","isPartOf":{"@id":"https:\/\/airport-clinic.de\/en\/#website"},"datePublished":"2023-01-30T12:09:54+00:00","dateModified":"2023-01-30T12:11:33+00:00","author":{"@id":"https:\/\/airport-clinic.de\/en\/#\/schema\/person\/43538e821127f36ed10b3d5e3709b3e3"},"breadcrumb":{"@id":"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/airport-clinic.de\/schmerzfreie-zahnbehandlung-bei-angstpatienten-dr-andreas-jauch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/airport-clinic.de\/"},{"@type":"ListItem","position":2,"name":"Schmerzfreie Zahnbehandlung bei Angstpatienten: Dr. Andreas Jauch"}]},{"@type":"WebSite","@id":"https:\/\/airport-clinic.de\/en\/#website","url":"https:\/\/airport-clinic.de\/en\/","name":"AirportClinic Freising","description":"Zentrum f\u00fcr Zahn-, Mund-, Kieferheilkunde und \u00e4sthetische Chirurgie MVZ GmbH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/airport-clinic.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/airport-clinic.de\/en\/#\/schema\/person\/43538e821127f36ed10b3d5e3709b3e3","name":"Dr. med. Andreas Jauch","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/airport-clinic.de\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4c61a56fd3071af7ddad2b2f0dd7ba04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c61a56fd3071af7ddad2b2f0dd7ba04?s=96&d=mm&r=g","caption":"Dr. med. Andreas Jauch"}}]}},"_links":{"self":[{"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/posts\/5198"}],"collection":[{"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/comments?post=5198"}],"version-history":[{"count":2,"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/posts\/5198\/revisions"}],"predecessor-version":[{"id":5201,"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/posts\/5198\/revisions\/5201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/media\/5180"}],"wp:attachment":[{"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/media?parent=5198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/categories?post=5198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/airport-clinic.de\/en\/wp-json\/wp\/v2\/tags?post=5198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}